{"id":121466,"date":"2018-07-18T16:34:31","date_gmt":"2018-07-18T15:34:31","guid":{"rendered":"https:\/\/www.realites.com.tn\/?p=121466"},"modified":"2018-07-19T09:33:37","modified_gmt":"2018-07-19T08:33:37","slug":"agir-sur-les-vraies-causes-du-terrorisme","status":"publish","type":"post","link":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/","title":{"rendered":"Agir sur les vraies causes du terrorisme"},"content":{"rendered":"<p>Il ne suffit pas de dire \u00eatre contre le terrorisme et le manifester par des slogans creux et des marches qui rel\u00e8vent, au mieux, de la pure agitation. On sait d\u2019ailleurs que ce sont les menteurs qui sont les plus actifs dans le ramage en vue de tromper sur leur plumage.<\/p>\n<p><strong>Un terrorisme mental<br \/>\n<\/strong>Le plumage terroriste est loin de se limiter aux crimes que nous continuons malheureusement \u00e0 d\u00e9plorer sur notre sol o\u00f9 des mains criminelles et occultes saignent \u00e0 blanc d&rsquo;innocentes et nombreuses victimes. Il est aussi et surtout dans la t\u00eate de certaines de nos \u00e9lites, parmi celles qui n\u2019osent dire les choses telles qu\u2019elles sont ni pointer le doigt sur le vrai terrorisme, celui qui se niche dans des mentalit\u00e9s r\u00e9trogrades faisant d&rsquo;une foi de paix, l&rsquo;islam, une religion de haine et de banditisme.<br \/>\nC&rsquo;est bien le cas pour qui continue de croire et d&rsquo;affirmer le jihad arm\u00e9, petit jihad au vrai, encore licite en islam, justifiant directement ou indirectement les forfaits de ces terroristes qui se r\u00e9clament d&rsquo;une telle perversion de l&rsquo;effort devant \u00eatre d&rsquo;abord et exclusivement sur soi.<br \/>\nOr, nous avons vu et voyons encore des philosophes, d\u00e9put\u00e9s, avocats, juges et politiciens, de chez nous et d&rsquo;ailleurs, qui persistent et signent \u00e0 d\u00e9fendre un tel jihad vici\u00e9, devenu cet usage truand des armes en dehors du seul usage licite qui est d\u00e9sormais le sien: le recours \u00e0 une violence l\u00e9gitime et l\u00e9gale, manifestation de l\u2019autorit\u00e9 de l&rsquo;\u00c9tat.<br \/>\nC\u2019est bien ce que fut le jihad au d\u00e9but de l\u2019islam, ayant \u00e9t\u00e9 l&rsquo;\u0153uvre du nouvel \u00c9tat de l&rsquo;islam; et c&rsquo;est ce qu&rsquo;il doit \u00eatre plus que jamais de nos jours : une pr\u00e9rogative d\u2019usage de la force publique en tant qu&rsquo;attribut du pouvoir l\u00e9galement organis\u00e9.<br \/>\nPourquoi donc ne pas en parler de la sorte afin d\u2019enlever leur justification aux terroristes qui se pr\u00e9sentent comme les d\u00e9fenseurs de l\u2019islam d\u00e9voy\u00e9 ? Ne le faisant pas, ne risque-t-on pas de nous r\u00e9v\u00e9ler les complices objectifs des terroristes ?<br \/>\nQu\u2019est-ce qui emp\u00eache de rompre avec la fausse conception du jihad qui s\u2019est impos\u00e9e \u00e0 tort dans les t\u00eates, y compris celles qui sont cens\u00e9es \u00eatre bien faites, inconscientes des effets n\u00e9fastes d\u2019une telle lecture erron\u00e9e de l\u2019islam qui, non seulement d\u00e9sinforme, mais influence certains jeunes d\u00e9sax\u00e9s en leur donnant un pr\u00e9texte commode \u00e0 leurs folies meurtri\u00e8res ?<\/p>\n<p><strong>Le vrai Jihad<br \/>\n<\/strong>Le jihad du d\u00e9but de l&rsquo;islam, fut un effort mineur, <em>jihad asghar<\/em>, et il est forclos depuis l\u2019\u00e9rection des \u00c9tats d\u2019islam et la stabilisation de la foi dans les c\u0153urs. En effet, tout comme l\u2019\u00e9migration, la <em>hijra<\/em>, il a pris fin; qui donc appellerait aujourd&rsquo;hui \u00e0 \u00e9migrer \u00e0 La Mecque ?<br \/>\nAussi, il ne reste plus de licite en islam que le <em>jihad akbar<\/em>, l&rsquo;effort maximal, qui concerne exclusivement l\u2019individu et qui est pacifiste, se passant de la moindre arme ou tout soup\u00e7on de violence, n\u2019\u00e9tant que l\u2019exemple insigne \u00e0 donner. C\u2019est cela l&rsquo;unique jihad licite en islam, seul vrai jihad d\u00e9sormais. Car l\u2019islam est la foi de la paix, ce que l&rsquo;on devrait orthographier <em>islam<\/em>, insistant sur sa dimension pacifique, afin de le sortir de la pratique actuelle en ayant fait une religion de guerre.<br \/>\nAgir, aujourd&rsquo;hui, en Tunisie, sur la cause du terrorisme, c\u2019est oser enfin parler des aspects tabous chez nous, dont ceux concernant cette alt\u00e9ration grotesque de notre religion qui en fait une foi obscurantiste et criminelle. Veut-on donc que Daech s\u2019installe en Tunisie?<br \/>\nN&rsquo;est-il pas temps d&rsquo;oser dire que cet Ant\u00e9-islam qu&rsquo;est Daech se recommande de la jurisprudence classique de l\u2019islam, ce m\u00eame fiqh auquel nous persistons \u00e0 nous r\u00e9f\u00e9rer bien qu&rsquo;il soit, dans nombre de ses aspects, devenu obsol\u00e8te et m\u00eame criminog\u00e8ne? Sait-on qu&rsquo;il y est prescrit de tuer le musulman qui ne prie pas; doit-on d\u00e9f\u00e9rer \u00e0 une telle monstruosit\u00e9 ?<br \/>\nEn notre patrie sinistr\u00e9e par la d\u00e9mission de ses clercs, c&rsquo;est bien le moment de rompre avec la fausse conception de notre foi qui y est d\u00e9fendue par des esprits inconscients pour le moins et qui n&rsquo;a perdur\u00e9 que parce qu&rsquo;elle a \u00e9t\u00e9 instrumentalis\u00e9e par des pouvoirs dictatoriaux ayant assur\u00e9 leur autorit\u00e9 en recourant \u00e0 un islam policier, mouture arabe de la religion opium du peuple.<\/p>\n<p><strong>Pour un islam polic\u00e9<br \/>\n<\/strong>En Tunisie post-r\u00e9volutionnaire, sept ans apr\u00e8s son coup du peuple et qui est de nouveau endeuill\u00e9e, on ne peut plus ni garder ni d\u00e9fendre la fausse lecture de l\u2019islam y ayant cours. L&rsquo;imp\u00e9ratif cat\u00e9gorique du moment est de rouvrir les portes pour une nouvelle ex\u00e9g\u00e8se de notre foi. <em>L&rsquo;ijtihad<\/em>, rappelons-le, a \u00e9t\u00e9 ferm\u00e9 au moment m\u00eame o\u00f9 a commenc\u00e9 le d\u00e9clin de la civilisation de l\u2019islam, et a manifest\u00e9 le pr\u00e9lude \u00e0 l\u2019installation durable de l\u2019imp\u00e9rialisme.<br \/>\nCe dernier, d\u2019ailleurs, a assur\u00e9 sa mainmise sur les pays d\u2019islam gr\u00e2ce \u00e0 la compromission des jurisconsultes et l\u2019alt\u00e9ration des principes humanistes et libertaires de l\u2019islam originel par des jurisconsultes <em>salafistes <\/em>veillant, au nom de la pr\u00e9servation de leur foi, \u00e0 ce qu\u2019elle se fige sur ce que les anc\u00eatres avaient arr\u00eat\u00e9 comme v\u00e9rit\u00e9.<br \/>\nOr, un tel effort d\u2019interpr\u00e9tation \u00e9tait d\u00e9j\u00e0 forc\u00e9ment imparfait et contingent, en plus d\u2019\u00eatre fortement marqu\u00e9 par la tradition jud\u00e9o-chr\u00e9tienne. Ce qui a fait que les musulmans se sont retrouv\u00e9s \u00e0 appliquer, au travers de leur <em>fiqh<\/em> traditionnel, bien plus la Bible que le Coran. Cela a \u00e9t\u00e9 amplifi\u00e9 par une v\u00e9ritable industrie des <em>hadiths<\/em> qui a march\u00e9 \u00e0 plein r\u00e9gime, inventant un autre islam parall\u00e8le au seul vrai, celui que rec\u00e8le le Coran o\u00f9 l&rsquo;islam est moins policier que polic\u00e9.<br \/>\nC&rsquo;est ainsi, \u00e0 titre d&rsquo;exemple, qu&rsquo;on a invent\u00e9 l\u2019interdiction de l\u2019alcool, alors que le Coran ne prohibe que l\u2019ivresse. Ainsi a-t-on- impos\u00e9 le je\u00fbne public alors que la vraie pi\u00e9t\u00e9 se cache et ne doit pas \u00eatre affich\u00e9e. Ainsi a-t-on prohib\u00e9 \u00e9galement les plantes hallucinog\u00e8nes, comme le cannabis, ou interdit les rapports entre m\u00eames sexes, alors qu\u2019il n\u2019est nulle interdiction en la mati\u00e8re ni expresse ni implicite dans la lettre du Coran. Ainsi, surtout s\u2019est-on permis d\u2019interpr\u00e9ter les pr\u00e9ceptes coraniques qui ne sont que des droits et des libert\u00e9s pour ce qui touche \u00e0 la libert\u00e9 priv\u00e9e, dans le sens restrictif, interdisant le sexe hors mariage\u00a0 ou l\u2019\u00e9galit\u00e9 successorale en dehors des vis\u00e9es de la loi religieuse qui supposent leur parfaite possibilit\u00e9 et m\u00eame fatalit\u00e9.<br \/>\nTout cela, et bien d&rsquo;autres aberrations qui forment le corpus du droit et de la jurisprudence actuels de notre <em>fiqh<\/em> traditionnel, a g\u00e9n\u00e9r\u00e9 un islam alt\u00e9r\u00e9, corrompu m\u00eame, auquel les int\u00e9gristes tiennent comme on tiendrait \u00e0 une arme fatale pour tout se permettre au nom de l\u2019islam.<br \/>\nC\u2019est ce que font exactement les terroristes qui se disent jihadistes, ou m\u00eame certains \u00c9tats voyous \u00e9rigeant une sorte de guerre sainte en islam alors que cette religion ne\u00a0 conna\u00eet point un tel concept, un produit des religions juda\u00efque et chr\u00e9tienne introduit en islam<br \/>\nAussi, en Tunisie et ailleurs en terre d&rsquo;islam, lutter contre le terrorisme physique suppose le plus imp\u00e9rativement de commencer d\u00e9j\u00e0 par un tel terrorisme qui est plus facile \u00e0 \u00e9radiquer puisqu\u2019il est nich\u00e9 dans les t\u00eates et que des lois justes, v\u00e9ritablement \u00e9thiques, peuvent en venir \u00e0 bout tout autant, pour commencer, que l\u2019abolition des textes sc\u00e9l\u00e9rats qui en sont la manifestation.<br \/>\nEn notre Tunisie qui risque de basculer \u00e0 tout moment dans l&rsquo;innommable, ce serait salutaire et radical pour contrer le terrorisme, car cela enl\u00e8vera aux suppos\u00e9s jihadistes, pour le moins cette aura usurp\u00e9e qu\u2019ils ont et qui leur permet\u00a0 d\u2019avoir \u2014 h\u00e9 oui ! \u2014 de la sympathie aupr\u00e8s de nombre de nos concitoyens, y compris aupr\u00e8s de certains responsables bien irresponsables parmi nos \u00e9lites.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ne suffit pas de dire \u00eatre contre le terrorisme et le manifester par des slogans creux et des marches qui rel\u00e8vent, au mieux, de la pure agitation. On sait&hellip;<\/p>\n","protected":false},"author":69,"featured_media":112208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-121466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agir sur les vraies causes du terrorisme - R\u00e9alit\u00e9s Magazine<\/title>\n<meta name=\"description\" content=\"Il ne suffit pas de dire \u00eatre contre le terrorisme et le manifester par des slogans creux et des marches qui rel\u00e8vent, au mieux, de la pure agitation. On\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agir sur les vraies causes du terrorisme - R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"og:description\" content=\"Il ne suffit pas de dire \u00eatre contre le terrorisme et le manifester par des slogans creux et des marches qui rel\u00e8vent, au mieux, de la pure agitation. On\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realites.tn\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-18T15:34:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-19T08:33:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2018\/04\/fo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Farhat Othman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Farhat Othman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/\",\"url\":\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/\",\"name\":\"Agir sur les vraies causes du terrorisme - R\u00e9alit\u00e9s Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2018\/04\/fo.jpg\",\"datePublished\":\"2018-07-18T15:34:31+00:00\",\"dateModified\":\"2018-07-19T08:33:37+00:00\",\"author\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/3f8af9442613ad4b53999cfd70f7f91d\"},\"description\":\"Il ne suffit pas de dire \u00eatre contre le terrorisme et le manifester par des slogans creux et des marches qui rel\u00e8vent, au mieux, de la pure agitation. On\",\"breadcrumb\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#primaryimage\",\"url\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2018\/04\/fo.jpg\",\"contentUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2018\/04\/fo.jpg\",\"width\":555,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/realites.com.tn\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agir sur les vraies causes du terrorisme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\",\"url\":\"https:\/\/realites.com.tn\/fr\/\",\"name\":\"R\u00e9alit\u00e9s Magazine\",\"description\":\"Actualit\u00e9s de la Tunisie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/realites.com.tn\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/3f8af9442613ad4b53999cfd70f7f91d\",\"name\":\"Farhat Othman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1abebddf4cecd056ea61d2dcf88d5a9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1abebddf4cecd056ea61d2dcf88d5a9d?s=96&d=mm&r=g\",\"caption\":\"Farhat Othman\"},\"url\":\"https:\/\/realites.com.tn\/fr\/author\/farhat-othman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agir sur les vraies causes du terrorisme - R\u00e9alit\u00e9s Magazine","description":"Il ne suffit pas de dire \u00eatre contre le terrorisme et le manifester par des slogans creux et des marches qui rel\u00e8vent, au mieux, de la pure agitation. On","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/","og_locale":"fr_FR","og_type":"article","og_title":"Agir sur les vraies causes du terrorisme - R\u00e9alit\u00e9s Magazine","og_description":"Il ne suffit pas de dire \u00eatre contre le terrorisme et le manifester par des slogans creux et des marches qui rel\u00e8vent, au mieux, de la pure agitation. On","og_url":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/","og_site_name":"R\u00e9alit\u00e9s Magazine","article_publisher":"https:\/\/www.facebook.com\/realites.tn\/","article_published_time":"2018-07-18T15:34:31+00:00","article_modified_time":"2018-07-19T08:33:37+00:00","og_image":[{"width":555,"height":500,"url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2018\/04\/fo.jpg","type":"image\/jpeg"}],"author":"Farhat Othman","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Farhat Othman","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/","url":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/","name":"Agir sur les vraies causes du terrorisme - R\u00e9alit\u00e9s Magazine","isPartOf":{"@id":"https:\/\/realites.com.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#primaryimage"},"image":{"@id":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#primaryimage"},"thumbnailUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2018\/04\/fo.jpg","datePublished":"2018-07-18T15:34:31+00:00","dateModified":"2018-07-19T08:33:37+00:00","author":{"@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/3f8af9442613ad4b53999cfd70f7f91d"},"description":"Il ne suffit pas de dire \u00eatre contre le terrorisme et le manifester par des slogans creux et des marches qui rel\u00e8vent, au mieux, de la pure agitation. On","breadcrumb":{"@id":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#primaryimage","url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2018\/04\/fo.jpg","contentUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2018\/04\/fo.jpg","width":555,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/realites.com.tn\/fr\/agir-sur-les-vraies-causes-du-terrorisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/realites.com.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Agir sur les vraies causes du terrorisme"}]},{"@type":"WebSite","@id":"https:\/\/realites.com.tn\/fr\/#website","url":"https:\/\/realites.com.tn\/fr\/","name":"R\u00e9alit\u00e9s Magazine","description":"Actualit\u00e9s de la Tunisie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realites.com.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/3f8af9442613ad4b53999cfd70f7f91d","name":"Farhat Othman","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1abebddf4cecd056ea61d2dcf88d5a9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1abebddf4cecd056ea61d2dcf88d5a9d?s=96&d=mm&r=g","caption":"Farhat Othman"},"url":"https:\/\/realites.com.tn\/fr\/author\/farhat-othman\/"}]}},"jetpack_featured_media_url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2018\/04\/fo.jpg","jetpack_sharing_enabled":true,"views":17,"_links":{"self":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/121466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/comments?post=121466"}],"version-history":[{"count":0,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/121466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media\/112208"}],"wp:attachment":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media?parent=121466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/categories?post=121466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/tags?post=121466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}