{"id":337707,"date":"2024-11-08T13:30:45","date_gmt":"2024-11-08T12:30:45","guid":{"rendered":"https:\/\/realites.com.tn\/fr\/?p=337707"},"modified":"2024-11-08T13:30:45","modified_gmt":"2024-11-08T12:30:45","slug":"dereglements-climatiques-quavons-nous-prepare","status":"publish","type":"post","link":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/","title":{"rendered":"D\u00e9r\u00e8glements climatiques\u00a0: Qu\u2019avons-nous pr\u00e9par\u00e9\u00a0?"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Les inondations meurtri\u00e8res et historiques qui viennent de frapper l\u2019Espagne ne sont pas le fait du hasard. Les d\u00e9r\u00e8glements climatiques sont une r\u00e9alit\u00e9 \u00e0 l\u2019\u00e9chelle mondiale stigmatis\u00e9e par les experts internationaux depuis plus de trois d\u00e9cennies. Le Bassin m\u00e9diterran\u00e9en est une des r\u00e9gions les plus menac\u00e9es par une s\u00e9cheresse critique, par le stress hydrique et par les inondations et les crues. Sommes-nous pr\u00e9par\u00e9s, en Tunisie, \u00e0 y faire face avec le moins de d\u00e9g\u00e2ts possibles\u00a0?<\/em><\/p>\n<p><strong>\u00a0<\/strong>La Tunisie est, \u00e0 l\u2019instar des autres pays, expos\u00e9e aux ph\u00e9nom\u00e8nes naturels extr\u00eames. Souvent d\u2019ampleur impr\u00e9visible, l\u2019adaptation et la pr\u00e9vention demeurent les seules solutions possibles pour en att\u00e9nuer l\u2019impact sur les populations et sur les \u00e9conomies nationales. Le monde s\u2019est mobilis\u00e9 d\u00e8s les ann\u00e9es 90 pour contrer les dysfonctionnements de la nature constat\u00e9s et point\u00e9s par des experts internationaux qui ont \u00e9t\u00e9 rassembl\u00e9s en 1988 dans un Groupe scientifique d\u2019experts intergouvernemental, le GIEC, charg\u00e9 de suivre l\u2019\u00e9volution du climat, d\u2019en \u00e9valuer l\u2019ampleur, les causes et les cons\u00e9quences. Plusieurs m\u00e9canismes ont \u00e9t\u00e9 mis en place pour r\u00e9pondre \u00e0 la demande pressante des experts de s\u2019y pr\u00e9parer avant qu\u2019il ne soit trop tard.<br \/>\nLes institutions onusiennes ont \u00e9t\u00e9 les plus r\u00e9ceptives et les plus actives dans ce domaine, plusieurs conventions internationales de lutte contre les causes des changements climatiques ont \u00e9t\u00e9 \u00e9labor\u00e9es et propos\u00e9es aux gouvernements pour leur adoption et surtout leur ex\u00e9cution. Un de ces m\u00e9canismes est la Convention des Parties \u00e0 la Convention-cadre des Nations unies sur les changements climatiques qui vient s\u2019ajouter \u00e0 une pr\u00e9c\u00e9dente s\u00e9rie d\u2019autres conventions plus sp\u00e9cifiques aux diff\u00e9rentes composantes des \u00e9cosyst\u00e8mes (sol, air, mer). La derni\u00e8re \u00e9dition de cette conf\u00e9rence des Nations unies sur les changements climatiques, COP 28, a eu lieu \u00e0 Duba\u00ef (Emirats arabes unis), l\u2019an dernier, du 30 novembre au 12 d\u00e9cembre 2023 (197 pays et 70 mille participants). Ses objectifs\u00a0: marquer \u00ab\u00a0<em>le d\u00e9but de la fin des combustibles fossiles<\/em>\u00a0\u00bb, principales causes, selon les experts, des \u00e9missions de gaz \u00e0 effet de serre, du r\u00e9chauffement de la temp\u00e9rature de la Terre, des \u00e9pisodes plus longs et plus critiques de la s\u00e9cheresse, de l\u2019augmentation du niveau de la mer. Concr\u00e8tement, ces d\u00e9r\u00e8glements aboutissent \u00e0 des \u00e9pisodes pluvieux rares et violents, aux inondations d\u00e9sormais de plus en plus meurtri\u00e8res, aux p\u00e9nuries d\u2019eau potable, \u00e0 la baisse des r\u00e9coltes et dans certaines r\u00e9gions, notamment africaines, aux famines.<br \/>\nDes accords internationaux ont pu voir le jour gr\u00e2ce \u00e0 la mobilisation onusienne et gouvernementale. Le dernier plus important d\u2019entre eux est l\u2019Accord de Paris (2015) qui exhorte les pays \u00e0 agir pour contenir l\u2019\u00e9l\u00e9vation de la temp\u00e9rature terrestre \u00e0 1,5 degr\u00e9 celsius, ce qui implique la r\u00e9duction de pr\u00e8s de moiti\u00e9 (43%) les \u00e9missions mondiales des gaz \u00e0 effet de serre d\u2019ici \u00e0 2030. Ce qui suppose que chaque gouvernement respecte sa part de responsabilit\u00e9 et d\u2019engagement pour atteindre ces objectifs.<br \/>\nA ce jour, si l\u2019on consid\u00e8re l\u2019\u00e9volution du climat, la fr\u00e9quence (plus grande) des catastrophes climatiques et la multiplication des guerres et leur impact sur la pollution de l\u2019air et du sol, il est \u00e9vident que les pays signataires ne respectent pas leurs engagements quand d\u2019autres, comme les Etats-Unis sous la pr\u00e9sidence de Trump (2016-2020) , mettent en doute carr\u00e9ment la rh\u00e9torique du GIEC.<br \/>\nLa Tunisie a \u00e9t\u00e9, d\u00e8s le d\u00e9part, partie prenante dans la mobilisation mondiale pour la protection de l\u2019environnement et pour la lutte contre les changements climatiques. La Convention-cadre des Nations unies sur les changements climatiques (CCNUCC) a \u00e9t\u00e9 ratifi\u00e9e en 1993, le Protocole de Kyoto (Japon) en 2002 et le Protocole de Paris en 2016. Mais qu\u2019est-ce que la Tunisie a r\u00e9alis\u00e9, dans la durabilit\u00e9,\u00a0au profit de la transition \u00e9cologique ?<\/p>\n<p><strong>\u00a0<\/strong><strong>Engagements internationaux et d\u00e9fis nationaux<br \/>\n<\/strong>En tant que pays membre signataire de la CCNUCC et des Accords inh\u00e9rents, la Tunisie est astreinte aux objectifs climatiques mondiaux. Mais, comme nombre d\u2019autres pays, la Tunisie fait face \u00e0 des d\u00e9fis nationaux sp\u00e9cifiques qui entravent sa marche vers une transition \u00e9nerg\u00e9tique et \u00e9cologique acc\u00e9l\u00e9r\u00e9e, tout en sachant que la Tunisie fait partie des bons \u00e9l\u00e8ves en mati\u00e8re de protection de l\u2019environnement. En 2021, et en vertu de l\u2019Accord de Paris, la Tunisie s\u2019est engag\u00e9e \u00e0 r\u00e9duire l\u2019intensit\u00e9 carbone de son \u00e9conomie, par rapport \u00e0 l\u2019ann\u00e9e de base 2010, de 45% en 2030 (contre un engagement de 41% en 2015). Un engagement qui implique des efforts particuliers d\u2019int\u00e9gration des indicateurs climatiques dans les politiques et les budgets publics, tels que la promotion des \u00e9nergies renouvelables, mais ces ambitions exigent des financements sup\u00e9rieurs aux capacit\u00e9s d\u2019investissement national et le recours \u00e0 des expertises internationales. D\u00e9fis que la COP tente de relever pour r\u00e9pondre aux difficult\u00e9s rencontr\u00e9es par tous les pays en voie de d\u00e9veloppement.<br \/>\nUn des enjeux de la derni\u00e8re COP28, \u00e9tait la finance climatique et les moyens de redynamiser le Fonds vert pour le climat, m\u00e9canisme financier de la CCNUCC, cr\u00e9\u00e9 en 2013. Ce Fonds repr\u00e9sente une opportunit\u00e9 pour la Tunisie d\u2019acc\u00e9der \u00e0 des ressources cons\u00e9quentes pour financer la mise en \u0153uvre de programmes et de strat\u00e9gies de lutte contre le changement climatique. En vertu des rapports officiels, dont la Quatri\u00e8me communication nationale de la Tunisie au titre de la CCNUCC en date de d\u00e9cembre 2023, les engagements nationaux sont transparents et franchement orient\u00e9s vers une vision globale \u00e0 la fois \u00e9nerg\u00e9tique, climatique et socio\u00e9conomique.<br \/>\nLe r\u00f4le social de l\u2019Etat est d\u00e9sormais une orientation strat\u00e9gique en Tunisie, ce qui implique de nouveaux d\u00e9fis \u00e9conomiques qu\u2019il incombe de relever. Outre l\u2019effort singulier de l\u2019Etat attendu en termes de transition \u00e9nerg\u00e9tique et de m\u00e9canismes financiers, juridiques et technologiques innovants d\u2019adaptation aux changements climatiques, les communes, la soci\u00e9t\u00e9 civile et le citoyen sont \u00e9galement appel\u00e9s \u00e0 participer dans le cadre d\u2019un effort national de pr\u00e9vention. Il s\u2019agit de contribuer \u00e0 l\u2019am\u00e9lioration des performances des strat\u00e9gies de gestion (collecte, tri, transformation) de toutes sortes de d\u00e9chets (m\u00e9nagers, industriels, hospitaliers\u2026), de renforcer le secteur de la valorisation des d\u00e9chets en vue de diminuer les quantit\u00e9s produites et de cr\u00e9er de nouveaux emplois dans le secteur environnemental et de pr\u00e9servation de l\u2019hygi\u00e8ne urbaine.<br \/>\nLes \u00e9chos des derni\u00e8res inondations qui ont frapp\u00e9 l\u2019Espagne d\u00e9passent les fronti\u00e8res hispaniques non seulement pour le nombre catastrophique de pertes humaines, plus de 217 morts et un nombre ind\u00e9termin\u00e9 de disparus, mais aussi pour la menace grandissante qui p\u00e8se sur le pourtour m\u00e9diterran\u00e9en. Plusieurs r\u00e9gions, dont la Tunisie, subissent depuis plusieurs ann\u00e9es une s\u00e9cheresse importante qui a entra\u00een\u00e9 des restrictions d\u2019eau, des feux de for\u00eat, des baisses ou des d\u00e9gradations de r\u00e9colte et, paradoxalement, des inondations et des crues meurtri\u00e8res. Sous l\u2019effet des changements climatiques, les experts pr\u00e9voient une aggravation des ph\u00e9nom\u00e8nes extr\u00eames auxquels il est imp\u00e9ratif de se pr\u00e9parer pour, au moins, en minimiser les d\u00e9g\u00e2ts.<br \/>\nDans ce domaine, il y a beaucoup \u00e0 faire en Tunisie et il devient, \u00e0 ce titre, urgent de proc\u00e9der \u00e0 l\u2019organisation de nouvelles \u00e9lections municipales pour institutionnaliser, coordonner et augmenter l\u2019efficacit\u00e9 des futures et urgentes interventions dans le domaine public communal. Le d\u00e9fi majeur pour tous les pays du monde continue d\u2019\u00eatre les actions pr\u00e9ventives mises en place pour \u00e9viter des h\u00e9catombes comme celle constat\u00e9e ces derniers jours dans le Sud de l\u2019Espagne. \u00a0Certaines de ces actions citoyennes sont simples, elles ne n\u00e9cessitent que de la volont\u00e9 et de l\u2019adh\u00e9sion.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les inondations meurtri\u00e8res et historiques qui viennent de frapper l\u2019Espagne ne sont pas le fait du hasard. Les d\u00e9r\u00e8glements climatiques sont une r\u00e9alit\u00e9 \u00e0 l\u2019\u00e9chelle mondiale stigmatis\u00e9e par les experts&hellip;<\/p>\n","protected":false},"author":107,"featured_media":337708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,9],"tags":[],"class_list":["post-337707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-societe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9r\u00e8glements climatiques\u00a0: Qu\u2019avons-nous pr\u00e9par\u00e9\u00a0? - R\u00e9alit\u00e9s Magazine<\/title>\n<meta name=\"description\" content=\"Les inondations meurtri\u00e8res et historiques qui viennent de frapper l\u2019Espagne ne sont pas le fait du hasard. Les d\u00e9r\u00e8glements climatiques sont une r\u00e9alit\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9r\u00e8glements climatiques\u00a0: Qu\u2019avons-nous pr\u00e9par\u00e9\u00a0? - R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"og:description\" content=\"Les inondations meurtri\u00e8res et historiques qui viennent de frapper l\u2019Espagne ne sont pas le fait du hasard. Les d\u00e9r\u00e8glements climatiques sont une r\u00e9alit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realites.tn\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T12:30:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2024\/11\/climat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"775\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yasmine Arabi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yasmine Arabi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/\",\"url\":\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/\",\"name\":\"D\u00e9r\u00e8glements climatiques\u00a0: Qu\u2019avons-nous pr\u00e9par\u00e9\u00a0? - R\u00e9alit\u00e9s Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2024\/11\/climat.jpg\",\"datePublished\":\"2024-11-08T12:30:45+00:00\",\"author\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/06a511b4d2fe915f476de4f87e6bb2c8\"},\"description\":\"Les inondations meurtri\u00e8res et historiques qui viennent de frapper l\u2019Espagne ne sont pas le fait du hasard. Les d\u00e9r\u00e8glements climatiques sont une r\u00e9alit\u00e9\",\"breadcrumb\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#primaryimage\",\"url\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2024\/11\/climat.jpg\",\"contentUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2024\/11\/climat.jpg\",\"width\":1240,\"height\":775,\"caption\":\"Reportage dans la ville de Paiporta, la zone z\u00e9ro la plus touch\u00e9e, avec plus de 100 victimes. La pr\u00e9sence de boue et des v\u00e9hicules accident\u00e9s ralenti consid\u00e9rablement la progression des secouirs ainsi que le travail de d\u00e9blayement et de nettoygae des b\u00e9n\u00e9voles. L'arm\u00e9e et les pompiers se concentrent sur le sauvetage des survivants coinc\u00e9s dans les d\u00e9combres.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/realites.com.tn\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9r\u00e8glements climatiques\u00a0: Qu\u2019avons-nous pr\u00e9par\u00e9\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\",\"url\":\"https:\/\/realites.com.tn\/fr\/\",\"name\":\"R\u00e9alit\u00e9s Magazine\",\"description\":\"Actualit\u00e9s de la Tunisie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/realites.com.tn\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/06a511b4d2fe915f476de4f87e6bb2c8\",\"name\":\"Yasmine Arabi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/72452549604596af346e7e0fd432b2db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/72452549604596af346e7e0fd432b2db?s=96&d=mm&r=g\",\"caption\":\"Yasmine Arabi\"},\"url\":\"https:\/\/realites.com.tn\/fr\/author\/yasmine-arabi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9r\u00e8glements climatiques\u00a0: Qu\u2019avons-nous pr\u00e9par\u00e9\u00a0? - R\u00e9alit\u00e9s Magazine","description":"Les inondations meurtri\u00e8res et historiques qui viennent de frapper l\u2019Espagne ne sont pas le fait du hasard. Les d\u00e9r\u00e8glements climatiques sont une r\u00e9alit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9r\u00e8glements climatiques\u00a0: Qu\u2019avons-nous pr\u00e9par\u00e9\u00a0? - R\u00e9alit\u00e9s Magazine","og_description":"Les inondations meurtri\u00e8res et historiques qui viennent de frapper l\u2019Espagne ne sont pas le fait du hasard. Les d\u00e9r\u00e8glements climatiques sont une r\u00e9alit\u00e9","og_url":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/","og_site_name":"R\u00e9alit\u00e9s Magazine","article_publisher":"https:\/\/www.facebook.com\/realites.tn\/","article_published_time":"2024-11-08T12:30:45+00:00","og_image":[{"width":1240,"height":775,"url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2024\/11\/climat.jpg","type":"image\/jpeg"}],"author":"Yasmine Arabi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Yasmine Arabi","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/","url":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/","name":"D\u00e9r\u00e8glements climatiques\u00a0: Qu\u2019avons-nous pr\u00e9par\u00e9\u00a0? - R\u00e9alit\u00e9s Magazine","isPartOf":{"@id":"https:\/\/realites.com.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#primaryimage"},"image":{"@id":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#primaryimage"},"thumbnailUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2024\/11\/climat.jpg","datePublished":"2024-11-08T12:30:45+00:00","author":{"@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/06a511b4d2fe915f476de4f87e6bb2c8"},"description":"Les inondations meurtri\u00e8res et historiques qui viennent de frapper l\u2019Espagne ne sont pas le fait du hasard. Les d\u00e9r\u00e8glements climatiques sont une r\u00e9alit\u00e9","breadcrumb":{"@id":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#primaryimage","url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2024\/11\/climat.jpg","contentUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2024\/11\/climat.jpg","width":1240,"height":775,"caption":"Reportage dans la ville de Paiporta, la zone z\u00e9ro la plus touch\u00e9e, avec plus de 100 victimes. La pr\u00e9sence de boue et des v\u00e9hicules accident\u00e9s ralenti consid\u00e9rablement la progression des secouirs ainsi que le travail de d\u00e9blayement et de nettoygae des b\u00e9n\u00e9voles. L'arm\u00e9e et les pompiers se concentrent sur le sauvetage des survivants coinc\u00e9s dans les d\u00e9combres."},{"@type":"BreadcrumbList","@id":"https:\/\/realites.com.tn\/fr\/dereglements-climatiques-quavons-nous-prepare\/amp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/realites.com.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9r\u00e8glements climatiques\u00a0: Qu\u2019avons-nous pr\u00e9par\u00e9\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/realites.com.tn\/fr\/#website","url":"https:\/\/realites.com.tn\/fr\/","name":"R\u00e9alit\u00e9s Magazine","description":"Actualit\u00e9s de la Tunisie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realites.com.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/06a511b4d2fe915f476de4f87e6bb2c8","name":"Yasmine Arabi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/72452549604596af346e7e0fd432b2db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72452549604596af346e7e0fd432b2db?s=96&d=mm&r=g","caption":"Yasmine Arabi"},"url":"https:\/\/realites.com.tn\/fr\/author\/yasmine-arabi\/"}]}},"jetpack_featured_media_url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2024\/11\/climat.jpg","jetpack_sharing_enabled":true,"views":178,"_links":{"self":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/337707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/users\/107"}],"replies":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/comments?post=337707"}],"version-history":[{"count":1,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/337707\/revisions"}],"predecessor-version":[{"id":337709,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/337707\/revisions\/337709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media\/337708"}],"wp:attachment":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media?parent=337707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/categories?post=337707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/tags?post=337707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}