{"id":362299,"date":"2025-07-03T14:02:57","date_gmt":"2025-07-03T13:02:57","guid":{"rendered":"https:\/\/realites.com.tn\/fr\/?p=362299"},"modified":"2025-07-03T14:04:20","modified_gmt":"2025-07-03T13:04:20","slug":"tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee","status":"publish","type":"post","link":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/","title":{"rendered":"Tout savoir sur les r\u00e9sultats du Concours de la 9\u00e8me ann\u00e9e"},"content":{"rendered":"<div>\n<div dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"80a8205c-7643-4bad-9517-25498aaea9a1\" data-message-model-slug=\"gpt-4o\">\n<p data-start=\"66\" data-end=\"235\">Le minist\u00e8re de l\u2019\u00c9ducation a annonc\u00e9, ce jeudi 3 juillet, les r\u00e9sultats du concours national d\u2019acc\u00e8s \u00e0 la 9e ann\u00e9e de l\u2019enseignement de base pour l\u2019ann\u00e9e scolaire 2025.<br \/>\nSelon les donn\u00e9es officielles, 16 290 candidats ont \u00e9t\u00e9 d\u00e9clar\u00e9s admis, soit un taux de r\u00e9ussite de 63,07 %. Parmi eux, 4 287 \u00e9l\u00e8ves ont \u00e9t\u00e9 orient\u00e9s vers les lyc\u00e9es pilotes. La meilleure moyenne au niveau national a \u00e9t\u00e9 obtenue par le candidat Kobe\u00efs Ben Sassi, \u00e9l\u00e8ve du coll\u00e8ge pilote du Menzah 5.<br \/>\nConcernant le concours de la 9e ann\u00e9e technique, Youssef Omri s\u2019est distingu\u00e9 avec la meilleure moyenne, fix\u00e9e \u00e0 14,18. Le taux de r\u00e9ussite dans cette fili\u00e8re s\u2019\u00e9l\u00e8ve \u00e0 56,27 %, avec un total de 148 laur\u00e9ats.<\/p>\n<p data-start=\"66\" data-end=\"235\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-362302 aligncenter\" src=\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/515019656_1123396303155053_6052507190837395819_n-300x283.jpg\" alt=\"\" width=\"438\" height=\"413\" srcset=\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/515019656_1123396303155053_6052507190837395819_n-300x283.jpg 300w, https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/515019656_1123396303155053_6052507190837395819_n-1024x965.jpg 1024w, https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/515019656_1123396303155053_6052507190837395819_n-768x724.jpg 768w, https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/515019656_1123396303155053_6052507190837395819_n-1536x1448.jpg 1536w, https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/515019656_1123396303155053_6052507190837395819_n.jpg 1600w\" sizes=\"(max-width: 438px) 100vw, 438px\" \/><\/p>\n<\/div>\n<\/div>\n<div>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le minist\u00e8re de l\u2019\u00c9ducation a annonc\u00e9, ce jeudi 3 juillet, les r\u00e9sultats du concours national d\u2019acc\u00e8s \u00e0 la 9e ann\u00e9e de l\u2019enseignement de base pour l\u2019ann\u00e9e scolaire 2025. Selon les&hellip;<\/p>\n","protected":false},"author":60,"featured_media":362303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,9],"tags":[8913,4127,3736],"class_list":["post-362299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-societe","tag-concours-de-la-9eme-annee","tag-ministere-de-leducation","tag-realites-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tout savoir sur les r\u00e9sultats du Concours de la 9\u00e8me ann\u00e9e - R\u00e9alit\u00e9s Magazine<\/title>\n<meta name=\"description\" content=\"Le minist\u00e8re de l\u2019\u00c9ducation a annonc\u00e9, ce jeudi 3 juillet, les r\u00e9sultats du concours national d\u2019acc\u00e8s \u00e0 la 9e ann\u00e9e de l\u2019enseignement de base pour l\u2019ann\u00e9e\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tout savoir sur les r\u00e9sultats du Concours de la 9\u00e8me ann\u00e9e - R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"og:description\" content=\"Le minist\u00e8re de l\u2019\u00c9ducation a annonc\u00e9, ce jeudi 3 juillet, les r\u00e9sultats du concours national d\u2019acc\u00e8s \u00e0 la 9e ann\u00e9e de l\u2019enseignement de base pour l\u2019ann\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realites.tn\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-03T13:02:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T13:04:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/examens-850x491-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"491\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/\",\"url\":\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/\",\"name\":\"Tout savoir sur les r\u00e9sultats du Concours de la 9\u00e8me ann\u00e9e - R\u00e9alit\u00e9s Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/examens-850x491-1.jpg\",\"datePublished\":\"2025-07-03T13:02:57+00:00\",\"dateModified\":\"2025-07-03T13:04:20+00:00\",\"author\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/438b71c29a257d955d96d8aef42336e7\"},\"description\":\"Le minist\u00e8re de l\u2019\u00c9ducation a annonc\u00e9, ce jeudi 3 juillet, les r\u00e9sultats du concours national d\u2019acc\u00e8s \u00e0 la 9e ann\u00e9e de l\u2019enseignement de base pour l\u2019ann\u00e9e\",\"breadcrumb\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#primaryimage\",\"url\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/examens-850x491-1.jpg\",\"contentUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/examens-850x491-1.jpg\",\"width\":850,\"height\":491},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/realites.com.tn\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tout savoir sur les r\u00e9sultats du Concours de la 9\u00e8me ann\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\",\"url\":\"https:\/\/realites.com.tn\/fr\/\",\"name\":\"R\u00e9alit\u00e9s Magazine\",\"description\":\"Actualit\u00e9s de la Tunisie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/realites.com.tn\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/438b71c29a257d955d96d8aef42336e7\",\"name\":\"La R\u00e9daction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fbe9ab25fcc82b6e660ad5648f91eadb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fbe9ab25fcc82b6e660ad5648f91eadb?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction\"},\"url\":\"https:\/\/realites.com.tn\/fr\/author\/realites5201\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tout savoir sur les r\u00e9sultats du Concours de la 9\u00e8me ann\u00e9e - R\u00e9alit\u00e9s Magazine","description":"Le minist\u00e8re de l\u2019\u00c9ducation a annonc\u00e9, ce jeudi 3 juillet, les r\u00e9sultats du concours national d\u2019acc\u00e8s \u00e0 la 9e ann\u00e9e de l\u2019enseignement de base pour l\u2019ann\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/","og_locale":"fr_FR","og_type":"article","og_title":"Tout savoir sur les r\u00e9sultats du Concours de la 9\u00e8me ann\u00e9e - R\u00e9alit\u00e9s Magazine","og_description":"Le minist\u00e8re de l\u2019\u00c9ducation a annonc\u00e9, ce jeudi 3 juillet, les r\u00e9sultats du concours national d\u2019acc\u00e8s \u00e0 la 9e ann\u00e9e de l\u2019enseignement de base pour l\u2019ann\u00e9e","og_url":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/","og_site_name":"R\u00e9alit\u00e9s Magazine","article_publisher":"https:\/\/www.facebook.com\/realites.tn\/","article_published_time":"2025-07-03T13:02:57+00:00","article_modified_time":"2025-07-03T13:04:20+00:00","og_image":[{"width":850,"height":491,"url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/examens-850x491-1.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La R\u00e9daction","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/","url":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/","name":"Tout savoir sur les r\u00e9sultats du Concours de la 9\u00e8me ann\u00e9e - R\u00e9alit\u00e9s Magazine","isPartOf":{"@id":"https:\/\/realites.com.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#primaryimage"},"image":{"@id":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#primaryimage"},"thumbnailUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/examens-850x491-1.jpg","datePublished":"2025-07-03T13:02:57+00:00","dateModified":"2025-07-03T13:04:20+00:00","author":{"@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/438b71c29a257d955d96d8aef42336e7"},"description":"Le minist\u00e8re de l\u2019\u00c9ducation a annonc\u00e9, ce jeudi 3 juillet, les r\u00e9sultats du concours national d\u2019acc\u00e8s \u00e0 la 9e ann\u00e9e de l\u2019enseignement de base pour l\u2019ann\u00e9e","breadcrumb":{"@id":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#primaryimage","url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/examens-850x491-1.jpg","contentUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/examens-850x491-1.jpg","width":850,"height":491},{"@type":"BreadcrumbList","@id":"https:\/\/realites.com.tn\/fr\/tout-savoir-sur-les-resultats-du-concours-de-la-9eme-annee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/realites.com.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Tout savoir sur les r\u00e9sultats du Concours de la 9\u00e8me ann\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/realites.com.tn\/fr\/#website","url":"https:\/\/realites.com.tn\/fr\/","name":"R\u00e9alit\u00e9s Magazine","description":"Actualit\u00e9s de la Tunisie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realites.com.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/438b71c29a257d955d96d8aef42336e7","name":"La R\u00e9daction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fbe9ab25fcc82b6e660ad5648f91eadb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbe9ab25fcc82b6e660ad5648f91eadb?s=96&d=mm&r=g","caption":"La R\u00e9daction"},"url":"https:\/\/realites.com.tn\/fr\/author\/realites5201\/"}]}},"jetpack_featured_media_url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/07\/examens-850x491-1.jpg","jetpack_sharing_enabled":true,"views":488,"_links":{"self":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/362299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/comments?post=362299"}],"version-history":[{"count":1,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/362299\/revisions"}],"predecessor-version":[{"id":362304,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/362299\/revisions\/362304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media\/362303"}],"wp:attachment":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media?parent=362299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/categories?post=362299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/tags?post=362299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}