{"id":388937,"date":"2026-05-23T20:06:55","date_gmt":"2026-05-23T19:06:55","guid":{"rendered":"https:\/\/realites.com.tn\/fr\/?p=388937"},"modified":"2026-05-23T20:06:55","modified_gmt":"2026-05-23T19:06:55","slug":"elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee","status":"publish","type":"post","link":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/","title":{"rendered":"Elan de solidarit\u00e9 : plus de 1500 citoyens recouvrent la vue en une seule journ\u00e9e"},"content":{"rendered":"<p>Plac\u00e9e sous le slogan \u00ab La vue, lumi\u00e8re de la vie \u00bb, la deuxi\u00e8me \u00e9dition de la Journ\u00e9e nationale de la sant\u00e9 oculaire, qui s&rsquo;est d\u00e9roul\u00e9e ce samedi 23 mai, a d\u00e9bouch\u00e9 sur un exploit sanitaire et humanitaire sans pr\u00e9c\u00e9dent. En l\u2019espace de 24 heures, plus de 1500 op\u00e9rations chirurgicales gratuites de la cataracte ont \u00e9t\u00e9 pratiqu\u00e9es avec succ\u00e8s au profit de citoyens \u00e0 travers les diff\u00e9rents gouvernorats de la R\u00e9publique.<br \/>\nCe bilan exceptionnel d\u00e9passe de loin l&rsquo;objectif initialement fix\u00e9 \u00e0 1000 interventions. Par son ampleur et sa port\u00e9e profond\u00e9ment humanitaire, cette performance nationale s&rsquo;apparente d\u00e9sormais \u00e0 un v\u00e9ritable record mondial.<br \/>\nCette r\u00e9ussite m\u00e9dicale majeure est le fruit d&rsquo;une mobilisation nationale d&rsquo;envergure. Selon un communiqu\u00e9 publi\u00e9 par le minist\u00e8re de la Sant\u00e9, elle a f\u00e9d\u00e9r\u00e9 les efforts des corps m\u00e9dicaux, param\u00e9dicaux et administratifs, ainsi que des structures de sant\u00e9 publiques et priv\u00e9es, en \u00e9troite collaboration avec la soci\u00e9t\u00e9 civile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plac\u00e9e sous le slogan \u00ab La vue, lumi\u00e8re de la vie \u00bb, la deuxi\u00e8me \u00e9dition de la Journ\u00e9e nationale de la sant\u00e9 oculaire, qui s&rsquo;est d\u00e9roul\u00e9e ce samedi 23 mai,&hellip;<\/p>\n","protected":false},"author":144,"featured_media":388938,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,2515],"tags":[10853,10854,10855,3736],"class_list":["post-388937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-sante","tag-journee-nationale-de-la-sante","tag-la-vue","tag-lumiere-de-la-vie","tag-realites-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elan de solidarit\u00e9 : plus de 1500 citoyens recouvrent la vue en une seule journ\u00e9e - R\u00e9alit\u00e9s Magazine<\/title>\n<meta name=\"description\" content=\"Plac\u00e9e sous le slogan \u00ab La vue, lumi\u00e8re de la vie \u00bb, la deuxi\u00e8me \u00e9dition de la Journ\u00e9e nationale de la sant\u00e9 oculaire, qui s&#039;est d\u00e9roul\u00e9e ce samedi 23\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elan de solidarit\u00e9 : plus de 1500 citoyens recouvrent la vue en une seule journ\u00e9e - R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"og:description\" content=\"Plac\u00e9e sous le slogan \u00ab La vue, lumi\u00e8re de la vie \u00bb, la deuxi\u00e8me \u00e9dition de la Journ\u00e9e nationale de la sant\u00e9 oculaire, qui s&#039;est d\u00e9roul\u00e9e ce samedi 23\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realites.tn\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-23T19:06:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2026\/05\/706198623_1413410390829419_6908251271876557896_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WKB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WKB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/\",\"url\":\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/\",\"name\":\"Elan de solidarit\u00e9 : plus de 1500 citoyens recouvrent la vue en une seule journ\u00e9e - R\u00e9alit\u00e9s Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2026\/05\/706198623_1413410390829419_6908251271876557896_n.jpg\",\"datePublished\":\"2026-05-23T19:06:55+00:00\",\"author\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/3017fbbf260e8228acd3e8ebf0cdd37f\"},\"description\":\"Plac\u00e9e sous le slogan \u00ab La vue, lumi\u00e8re de la vie \u00bb, la deuxi\u00e8me \u00e9dition de la Journ\u00e9e nationale de la sant\u00e9 oculaire, qui s'est d\u00e9roul\u00e9e ce samedi 23\",\"breadcrumb\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#primaryimage\",\"url\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2026\/05\/706198623_1413410390829419_6908251271876557896_n.jpg\",\"contentUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2026\/05\/706198623_1413410390829419_6908251271876557896_n.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/realites.com.tn\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elan de solidarit\u00e9 : plus de 1500 citoyens recouvrent la vue en une seule journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\",\"url\":\"https:\/\/realites.com.tn\/fr\/\",\"name\":\"R\u00e9alit\u00e9s Magazine\",\"description\":\"Actualit\u00e9s de la Tunisie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/realites.com.tn\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/3017fbbf260e8228acd3e8ebf0cdd37f\",\"name\":\"WKB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/90f27863f4f5326a9b64d42421f4a20f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/90f27863f4f5326a9b64d42421f4a20f?s=96&d=mm&r=g\",\"caption\":\"WKB\"},\"url\":\"https:\/\/realites.com.tn\/fr\/author\/wkb2025\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elan de solidarit\u00e9 : plus de 1500 citoyens recouvrent la vue en une seule journ\u00e9e - R\u00e9alit\u00e9s Magazine","description":"Plac\u00e9e sous le slogan \u00ab La vue, lumi\u00e8re de la vie \u00bb, la deuxi\u00e8me \u00e9dition de la Journ\u00e9e nationale de la sant\u00e9 oculaire, qui s'est d\u00e9roul\u00e9e ce samedi 23","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Elan de solidarit\u00e9 : plus de 1500 citoyens recouvrent la vue en une seule journ\u00e9e - R\u00e9alit\u00e9s Magazine","og_description":"Plac\u00e9e sous le slogan \u00ab La vue, lumi\u00e8re de la vie \u00bb, la deuxi\u00e8me \u00e9dition de la Journ\u00e9e nationale de la sant\u00e9 oculaire, qui s'est d\u00e9roul\u00e9e ce samedi 23","og_url":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/","og_site_name":"R\u00e9alit\u00e9s Magazine","article_publisher":"https:\/\/www.facebook.com\/realites.tn\/","article_published_time":"2026-05-23T19:06:55+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2026\/05\/706198623_1413410390829419_6908251271876557896_n.jpg","type":"image\/jpeg"}],"author":"WKB","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WKB","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/","url":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/","name":"Elan de solidarit\u00e9 : plus de 1500 citoyens recouvrent la vue en une seule journ\u00e9e - R\u00e9alit\u00e9s Magazine","isPartOf":{"@id":"https:\/\/realites.com.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#primaryimage"},"image":{"@id":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2026\/05\/706198623_1413410390829419_6908251271876557896_n.jpg","datePublished":"2026-05-23T19:06:55+00:00","author":{"@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/3017fbbf260e8228acd3e8ebf0cdd37f"},"description":"Plac\u00e9e sous le slogan \u00ab La vue, lumi\u00e8re de la vie \u00bb, la deuxi\u00e8me \u00e9dition de la Journ\u00e9e nationale de la sant\u00e9 oculaire, qui s'est d\u00e9roul\u00e9e ce samedi 23","breadcrumb":{"@id":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#primaryimage","url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2026\/05\/706198623_1413410390829419_6908251271876557896_n.jpg","contentUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2026\/05\/706198623_1413410390829419_6908251271876557896_n.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/realites.com.tn\/fr\/elan-de-solidarite-plus-de-1500-citoyens-recouvrent-la-vue-en-une-seule-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/realites.com.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Elan de solidarit\u00e9 : plus de 1500 citoyens recouvrent la vue en une seule journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/realites.com.tn\/fr\/#website","url":"https:\/\/realites.com.tn\/fr\/","name":"R\u00e9alit\u00e9s Magazine","description":"Actualit\u00e9s de la Tunisie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realites.com.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/3017fbbf260e8228acd3e8ebf0cdd37f","name":"WKB","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/90f27863f4f5326a9b64d42421f4a20f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90f27863f4f5326a9b64d42421f4a20f?s=96&d=mm&r=g","caption":"WKB"},"url":"https:\/\/realites.com.tn\/fr\/author\/wkb2025\/"}]}},"jetpack_featured_media_url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2026\/05\/706198623_1413410390829419_6908251271876557896_n.jpg","jetpack_sharing_enabled":true,"views":98,"_links":{"self":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/388937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/users\/144"}],"replies":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/comments?post=388937"}],"version-history":[{"count":1,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/388937\/revisions"}],"predecessor-version":[{"id":388939,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/388937\/revisions\/388939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media\/388938"}],"wp:attachment":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media?parent=388937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/categories?post=388937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/tags?post=388937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}