{"id":392241,"date":"2026-07-14T13:00:05","date_gmt":"2026-07-14T12:00:05","guid":{"rendered":"https:\/\/realites.com.tn\/fr\/?p=392241"},"modified":"2026-07-14T13:00:05","modified_gmt":"2026-07-14T12:00:05","slug":"la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international","status":"publish","type":"post","link":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/","title":{"rendered":"La force ou le droit ? Le d\u00e9troit d\u2019Ormuz et la mise \u00e0 l\u2019\u00e9preuve du syst\u00e8me international"},"content":{"rendered":"<p>Lorsque l\u2019Iran affirme \u00eatre en mesure de contr\u00f4ler le trafic dans le d\u00e9troit d\u2019Ormuz, et que les \u00c9tats-Unis ainsi que d\u2019autres pays refusent de reconna\u00eetre cette affirmation, le diff\u00e9rend ne porte pas sur un passage maritime en particulier, mais sur une question plus profonde qui touche au c\u0153ur m\u00eame du syst\u00e8me international : qui gouverne r\u00e9ellement le monde ? Est-ce la norme juridique ou l\u2019\u00e9quilibre des pouvoirs ? La r\u00e9ponse \u00e0 cette question r\u00e9v\u00e8le que le droit international, tel que nous le connaissons aujourd\u2019hui, n\u2019est qu\u2019une fine couche recouvrant une r\u00e9alit\u00e9 fa\u00e7onn\u00e9e par les grandes puissances.<\/p>\n<p><strong>\u00a0<\/strong><strong>Ce sont les vainqueurs qui ont \u00e9crit les r\u00e8gles<\/strong><\/p>\n<p>Pour comprendre cette paradoxale situation, il faut remonter au moment fondateur du syst\u00e8me international contemporain, en 1945. Le syst\u00e8me issu de la Seconde Guerre mondiale n\u2019a pas \u00e9t\u00e9 construit sur une neutralit\u00e9 juridique abstraite, mais sur un principe politique explicite : ce sont les vainqueurs qui fixent les r\u00e8gles. Ce sont les \u00c9tats-Unis, la Grande-Bretagne, la France et l\u2019Union sovi\u00e9tique qui ont r\u00e9dig\u00e9 la Charte des Nations unies, instaur\u00e9 le syst\u00e8me de s\u00e9curit\u00e9 collective, \u00e9tabli le principe de l\u2019interdiction de l\u2019acquisition de territoires par la force, d\u00e9fini la notion d\u2019agression et fond\u00e9 le syst\u00e8me des droits de l\u2019homme.<\/p>\n<p>Cependant, ces r\u00e8gles n\u2019ont pas \u00e9t\u00e9 r\u00e9dig\u00e9es dans un vide \u00e9thique, mais de mani\u00e8re \u00e0 servir les int\u00e9r\u00eats de leurs auteurs. Ils les ont r\u00e9dig\u00e9es de mani\u00e8re \u00e0 les rendre contraignantes pour les autres, tout en se r\u00e9servant une large marge de man\u0153uvre pour s\u2019en \u00e9carter lorsque cela s\u2019av\u00e8re n\u00e9cessaire. C\u2019est ainsi que le droit international est n\u00e9, charg\u00e9 d\u00e8s son origine d\u2019une contradiction structurelle: il pr\u00e9tend \u00e0 l\u2019universalit\u00e9, mais sert la particularit\u00e9 de la force.<\/p>\n<p><strong>Le veto : l\u2019expression explicite de la politique de la force<\/strong><\/p>\n<p>Cette contradiction se manifeste le plus clairement dans le droit de veto. Le fait que cinq \u00c9tats aient le pouvoir de bloquer n\u2019importe quelle d\u00e9cision internationale \u2014 quelle que soit sa l\u00e9gitimit\u00e9 juridique ou morale \u2014 signifie que l\u2019application du droit international n\u2019est pas une question de principe, mais qu\u2019elle d\u00e9pend des rapports de force au sein du Conseil de s\u00e9curit\u00e9.<\/p>\n<p>Le veto n\u2019est pas une faille du syst\u00e8me, mais le syst\u00e8me lui-m\u00eame : un m\u00e9canisme codifi\u00e9 garantissant que le droit ne s\u2019applique que lorsque la force le permet. Le droit n\u2019est pas abrog\u00e9, mais il est suspendu de mani\u00e8re tout \u00e0 fait l\u00e9gale lorsqu\u2019il se heurte aux int\u00e9r\u00eats des grandes puissances. Il en r\u00e9sulte que le droit international est appliqu\u00e9 \u00e0 la lettre aux plus faibles, tandis qu\u2019il devient une question facultative pour les plus puissants.<\/p>\n<p><strong>La force cr\u00e9e les faits sur le terrain, puis vient le droit<\/strong><\/p>\n<p>Depuis 1945, la pratique internationale a d\u00e9montr\u00e9 que la force militaire et \u00e9conomique est ce qui d\u00e9termine quelles dispositions du droit sont appliqu\u00e9es et lesquelles sont ignor\u00e9es. Les \u00c9tats-Unis sont ainsi intervenus militairement \u00e0 des dizaines de reprises en dehors de tout mandat onusien clair, de l\u2019Am\u00e9rique latine \u00e0 l\u2019Asie, jusqu\u2019\u00e0 l\u2019invasion de l\u2019Irak en 2003, et plus r\u00e9cemment le kidnapping du pr\u00e9sident du Venezuela. L\u2019Union sovi\u00e9tique, puis la F\u00e9d\u00e9ration de Russie, ont recouru \u00e0 la force dans leur p\u00e9rim\u00e8tre strat\u00e9gique, comme lors de l\u2019annexion de la Crim\u00e9e en 2014. La France et la Grande-Bretagne ont quant \u00e0 elles conserv\u00e9 un r\u00f4le militaire actif hors de leurs fronti\u00e8res. Dans tous ces cas, personne n\u2019a pu contraindre ces \u00c9tats \u00e0 respecter le droit international ; ils n\u2019ont \u00e9t\u00e9 ni sanctionn\u00e9s, ni jug\u00e9s, ni contraints de faire marche arri\u00e8re.<\/p>\n<p>C\u2019est l\u00e0 qu\u2019appara\u00eet clairement la r\u00e8gle fondamentale : \u00ab\u00a0la force cr\u00e9e les faits, les faits s\u2019imposent, puis le droit vient les l\u00e9gitimer ou s\u2019y adapter.\u00a0\u00bb La s\u00e9quence n\u2019est pas juridique, mais factuelle : l\u2019action pr\u00e9c\u00e8de la l\u00e9gitimation, et non l\u2019inverse. C\u2019est ce qu\u2019ont appliqu\u00e9 tant Netanyahou que Donald Trump dans les deux guerres qu\u2019ils ont men\u00e9es contre l\u2019Iran. Imaginez ce qui aurait pu se passer s\u2019ils avaient remport\u00e9 la guerre contre l\u2019Iran et r\u00e9ussi \u00e0 renverser le r\u00e9gime, comme cela s\u2019est produit en Irak ou au Venezuela.<\/p>\n<p>Un sc\u00e9nario de victoire impliquerait la nomination, \u00e0 la t\u00eate du nouveau r\u00e9gime, de la personne choisie par les \u00c9tats-Unis et Isra\u00ebl, la mainmise sur le p\u00e9trole iranien, le contr\u00f4le du d\u00e9troit d\u2019Ormuz (rappelons que le pr\u00e9sident am\u00e9ricain a \u00e9t\u00e9 le premier \u00e0 \u00e9voquer l\u2019id\u00e9e de faire payer une taxe de passage aux navires), et ainsi emp\u00eacher l\u2019approvisionnement en p\u00e9trole de la Chine comme cela s\u2019est produit au Venezuela, et parvenir aux fronti\u00e8res de la Russie (c\u2019est-\u00e0-dire, encercler ainsi la Russie et la Chine). Et cela, tout en obligeant les pays du Golfe \u00e0 verser une redevance mensuelle peut-\u00eatre, en les soumettant au chantage. De plus, cette op\u00e9ration redessinerait la carte de l\u2019ensemble du Moyen-Orient, l\u2019Iran devenant alors un pion docile entre les mains des \u00c9tats-Unis, comme \u00e0 l\u2019\u00e9poque du Shah.<\/p>\n<p>Mais ce sc\u00e9nario a \u00e9t\u00e9 contrecarr\u00e9 gr\u00e2ce \u00e0 la r\u00e9sistance iranienne et \u00e0 la vigilance chinoise et russe, le pr\u00e9sident Xi Jinping et Vladimir Poutine ayant tous deux compris les v\u00e9ritables objectifs vis\u00e9s par l\u2019occupant de la Maison Blanche.<\/p>\n<p><strong>Le cas isra\u00e9lien : un exemple de faits accomplis<\/strong><\/p>\n<p>Le cas isra\u00e9lien, depuis 78 ans, est peut-\u00eatre l\u2019incarnation la plus claire de la logique de la force. Depuis 1948, des faits g\u00e9opolitiques ont \u00e9t\u00e9 impos\u00e9s par la force : l\u2019occupation des territoires arabes au cours de plusieurs guerres non mentionn\u00e9es dans la r\u00e9solution de partition de l\u2019ONU (elle-m\u00eame fond\u00e9e sur la force, puisqu\u2019elle n\u2019a pas tenu compte de l\u2019avis des habitants palestiniens). L\u2019annexion de J\u00e9rusalem et du Golan. La construction de colonies en Cisjordanie, etc. Cela se poursuit encore aujourd\u2019hui avec l\u2019invasion de certaines parties de la Syrie et du Liban. Isra\u00ebl vise toujours \u00e0 prendre plus de terrains, alors que le droit international \u00a0rejette unanimement l\u2019ensemble de ces mesures.<\/p>\n<p>Mais qui va contraindre Isra\u00ebl \u00e0 se retirer ? Apr\u00e8s avoir enterr\u00e9 l\u2019Organisation de lib\u00e9ration de la Palestine \u00e0 Oslo et divis\u00e9 les Palestiniens en deux groupes\u00a0: l&rsquo;un, inerte, ob\u00e9issant aux ordres d\u2019Isra\u00ebl (l\u2019Autorit\u00e9 palestinienne) et combattant le deuxi\u00e8me groupe qui, continue de croire que la lib\u00e9ration passe par la lutte arm\u00e9e, \u00e0 l\u2019instar de l\u2019Alg\u00e9rie, du Vietnam, de la Chine et d\u2019autres pays jadis frapp\u00e9s par le fl\u00e9au de l\u2019occupation occidentale.<\/p>\n<p>Tout cela renvoie \u00e0 un fait historique : le monde consid\u00e8re la r\u00e9alit\u00e9 impos\u00e9e par la force comme la r\u00e9f\u00e9rence effective, et non le droit. Ainsi, le refus fond\u00e9 sur un principe juridique s\u2019est transform\u00e9 en une prise de position rh\u00e9torique, tandis que les faits sur le terrain sont rest\u00e9s la norme effective.<\/p>\n<p><strong>Le d\u00e9troit d\u2019Ormuz devenu le d\u00e9troit du destin<\/strong><\/p>\n<p>C\u2019est pr\u00e9cis\u00e9ment dans ce cadre que l\u2019on peut comprendre la position iranienne concernant le d\u00e9troit d\u2019Ormuz. D\u2019un point de vue juridique, le d\u00e9troit est consid\u00e9r\u00e9 comme une voie navigable internationale dont la circulation est r\u00e9gie par le principe du \u00ab passage en transit \u00bb, pr\u00e9vu par la Convention des Nations unies sur le droit de la mer de 1982, et qui ne peut \u00eatre ni interrompu ni suspendu. Par cons\u00e9quent, toute tentative de fermeture du d\u00e9troit ou d\u2019imposition de restrictions arbitraires \u00e0 son \u00e9gard constitue, en th\u00e9orie, une violation flagrante du droit international.<\/p>\n<p>Mais la r\u00e9alit\u00e9 est diff\u00e9rente. Apr\u00e8s deux guerres d\u2019agression contre l\u2019Iran, ce dernier a pris conscience que la logique de la force qui a pr\u00e9sid\u00e9 \u00e0 ces deux conflits (au cours desquels les Am\u00e9ricains et les Isra\u00e9liens ne se sont appuy\u00e9s sur aucune l\u00e9gitimit\u00e9 juridique) est pr\u00e9cis\u00e9ment celle qui impose la n\u00e9cessit\u00e9 de r\u00e9sister de la m\u00eame mani\u00e8re. Le d\u00e9troit \u00e9tait ouvert \u00e0 tous ; il est aujourd\u2019hui devenu un atout de n\u00e9gociation incontournable, sans lequel la position iranienne pourrait s&rsquo;effondrer. En effet, tout comme le d\u00e9troit est consid\u00e9r\u00e9 comme une art\u00e8re vitale pour l\u2019\u00e9conomie mondiale, il l\u2019est \u00e9galement pour la R\u00e9publique islamique, qui sait tr\u00e8s bien que le contr\u00f4ler, c\u2019est contr\u00f4ler son destin.<\/p>\n<p>L\u2019Iran dispose en effet d\u2019une position g\u00e9ographique dominante sur la rive nord du d\u00e9troit, ainsi que de capacit\u00e9s militaires \u2014 allant des mines marines aux vedettes rapides en passant par les missiles c\u00f4tiers \u2014 qui lui permettent d\u2019influencer concr\u00e8tement le trafic maritime par la menace, le harc\u00e8lement ou l\u2019imposition d\u2019un fait accompli. En revanche, les \u00c9tats-Unis ne peuvent imposer le respect total du droit dans ce d\u00e9troit qu\u2019en recourant \u00e0 une force de riposte, c\u2019est-\u00e0-dire en risquant de sombrer dans un affrontement militaire direct.<\/p>\n<p>Et la guerre \u2014 quelle qu\u2019elle soit \u2014 n\u2019offre aucune garantie quant \u00e0 ses cons\u00e9quences, comme l\u2019histoire continue de le d\u00e9montrer. Les deux guerres men\u00e9es par les \u00c9tats-Unis et Isra\u00ebl contre l\u2019Iran n\u2019ont pas suffi \u00e0 mettre le r\u00e9gime \u00e0 genoux. Au contraire, les fun\u00e9railles de l\u2019ayatollah Ali Khamenei, que Dieu lui fasse mis\u00e9ricorde, se sont transform\u00e9es en une manifestation de masse au cours de laquelle des foules comptant des millions de personnes ont r\u00e9clam\u00e9 vengeance pour son assassinat, tout en brandissant des slogans de soutien et de loyaut\u00e9 envers le r\u00e9gime de la R\u00e9publique islamique. Cet \u00e9v\u00e9nement a pris de court les plus farouches ennemis de l\u2019Iran, qui ne s\u2019attendaient pas \u00e0 ce que le r\u00e9gime iranien jouisse d\u2019une telle popularit\u00e9, alors qu\u2019ils pr\u00e9tendaient que les citoyens lui \u00e9taient hostiles. En r\u00e9alit\u00e9, comme le reconnaissent les analystes occidentaux, les fun\u00e9railles de Khamenei ont surpass\u00e9 toutes celles qui les ont pr\u00e9c\u00e9d\u00e9es dans l\u2019histoire moderne, de Kennedy \u00e0 Mahatma Gandhi en passant par Nasser et bien d\u2019autres.<\/p>\n<p>Un tel r\u00e9gime est-il donc vou\u00e9 \u00e0 tomber ? Les Am\u00e9ricains et les Isra\u00e9liens ont-ils encore l\u2019espoir de le renverser, d\u2019autant plus que Donald Trump avait accept\u00e9 les conditions de l\u2019Iran avant de revenir sur le protocole d\u2019accord ?<\/p>\n<p>En d\u2019autres termes, l\u2019Iran s\u2019appuie sur une double logique : il invoque le droit international lorsque celui-ci soutient sa souverainet\u00e9, mais s\u2019appuie en m\u00eame temps sur l\u2019\u00e9quilibre des forces pour se doter d\u2019une capacit\u00e9 de dissuasion qui rend sa menace cr\u00e9dible. Ce comportement ne diff\u00e8re pas fondamentalement de celui des grandes puissances ; il s\u2019inscrit pleinement dans la logique m\u00eame du syst\u00e8me international, et non pas en dehors de celui-ci. L\u2019Iran joue le m\u00eame jeu qu\u2019Isra\u00ebl, les \u00c9tats-Unis et les pays occidentaux. Il les tient \u00e0 la gorge en contr\u00f4lant le d\u00e9troit d\u2019Ormuz. Que pourraient-ils faire de plus qu\u2019ils n\u2019ont d\u00e9j\u00e0 fait ? S\u2019ils avaient pu infliger une d\u00e9faite cuisante aux Iraniens et leur imposer ensuite leurs conditions, pourquoi ne l\u2019auraient-ils pas fait ? La r\u00e9ponse r\u00e9side dans la r\u00e9alit\u00e9 elle-m\u00eame, qui montre que l\u2019Iran a mis les \u00c9tats-Unis et Isra\u00ebl dans une position d\u2019impuissance. Autrement dit, l\u2019Iran \u2014 l\u2019\u00c9tat cens\u00e9 \u00eatre \u00ab faible \u00bb dans ce syst\u00e8me \u2014 ma\u00eetrise d\u00e9sormais le jeu des grandes puissances : il fa\u00e7onne la r\u00e9alit\u00e9 par la force. Et plus il r\u00e9siste \u00e0 l\u2019agression, plus cette nouvelle r\u00e9alit\u00e9 s\u2019ancre sur le terrain.<\/p>\n<p><strong>Qui pourrait bien gagner la guerre ?<\/strong><\/p>\n<p>La guerre pourrait bien s\u00fbr reprendre sous une forme plus f\u00e9roce. Et comme nous le savons, c\u2019est celui qui a le plus de souffle qui remporte la guerre. Or, le temps joue actuellement en faveur de l\u2019Iran, et non en faveur de ses ennemis. Pourquoi ?<\/p>\n<p>Premi\u00e8rement, parce que T\u00e9h\u00e9ran a d\u00e9montr\u00e9 sa capacit\u00e9 \u00e0 r\u00e9sister et \u00e0 riposter, en rendant la pareille au centuple, ce qui a surpris tout le monde. Deuxi\u00e8mement, parce que l\u2019\u00e9l\u00e9ment le plus important dans une guerre, outre le facteur temps, est la force de volont\u00e9, qui puise sa source dans la popularit\u00e9 des dirigeants et le ralliement du peuple \u00e0 leur cause, ce qui les pousse \u00e0 aller de l\u2019avant pour atteindre les objectifs de la guerre, d&rsquo;autant plus que celle-ci leur est impos\u00e9e. Ce facteur joue \u00e9galement en faveur de l\u2019Iran. Apr\u00e8s avoir constat\u00e9 le ralliement du peuple iranien autour de ses dirigeants, il convient de comparer cela \u00e0 la situation chancelante de Donald Trump aux \u00c9tats-Unis et \u00e0 celle, non moins pr\u00e9caire, de Benjamin Netanyahou en Isra\u00ebl. Tous deux sont menac\u00e9s, lors des \u00e9lections de l\u2019automne prochain, de voir leur carri\u00e8re politique prendre fin, ce qui s\u2019accompagnerait de poursuites judiciaires et de proc\u00e8s. Troisi\u00e8mement, la clart\u00e9 de la vision. Ce facteur joue \u00e9galement en faveur de l\u2019Iran. Les Iraniens m\u00e8nent une guerre d\u00e9fensive existentielle et savent que la d\u00e9faite n\u2019est pas une option, mais un effondrement. Quant aux Am\u00e9ricains et aux Isra\u00e9liens, ils n\u2019ont aucune clart\u00e9 de vision. Combien de fois le pr\u00e9sident am\u00e9ricain a-t-il chang\u00e9 de discours lorsqu\u2019il parle de la guerre et de ses objectifs ? Quel objectif a-t-il atteint ? Il en va de m\u00eame pour Netanyahou. Il n\u2019a pas encore r\u00e9ussi \u00e0 atteindre son objectif : emp\u00eacher l\u2019Iran de poursuivre son programme nucl\u00e9aire. Peut-\u00eatre que le manque de clart\u00e9 de ces deux hommes tient au fait qu\u2019ils trompent leurs populations depuis le d\u00e9but : tous deux sont menac\u00e9s par la justice, et la guerre est venue faire oublier aux gens que Donald Trump est enlis\u00e9 jusqu\u2019au cou dans l\u2019affaire Epstein. Quant \u00e0 Netanyahou, il est demand\u00e9 par la justice en Isra\u00ebl, mais aussi \u00e0 l\u2019\u00e9tranger. Si cet \u00e9t\u00e9 s\u2019ach\u00e8ve sans qu\u2019ils aient remport\u00e9 une victoire \u00e9crasante sur l\u2019Iran, ce sera la fin de leur carri\u00e8re politique.<\/p>\n<p>En conclusion, le d\u00e9troit d\u2019Ormuz n\u2019est pas une exception, mais un exemple concentr\u00e9 de la r\u00e8gle g\u00e9n\u00e9rale qui r\u00e9git les relations internationales depuis 1945 : si le droit international d\u00e9finit ce qui devrait \u00eatre, seule la force d\u00e9termine ce qui est et ce qui doit \u00eatre. Et lorsque les deux s\u2019opposent, le dernier mot revient, la plupart du temps, \u00e0 celui qui a la capacit\u00e9 d\u2019imposer les faits sur le terrain \u2014 ou en mer, ou dans les airs.<\/p>\n<p>Il ne s\u2019agit pas l\u00e0 d\u2019une philosophie pessimiste, mais d\u2019une description pr\u00e9cise de la structure d\u2019un ordre international n\u00e9 des cendres de la guerre et qui reste r\u00e9gi par sa logique : c\u2019est la force qui dicte le droit, et non l\u2019inverse. Les grandes puissances restent au-dessus des lois, tandis que les petits \u00c9tats restent soumis \u00e0 celles-ci \u2014 sauf lorsqu\u2019ils parviennent, ne serait-ce que temporairement, \u00e0 renverser l\u2019\u00e9quation sur le terrain, comme l\u2019Iran tente de le faire dans le d\u00e9troit d\u2019Ormuz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque l\u2019Iran affirme \u00eatre en mesure de contr\u00f4ler le trafic dans le d\u00e9troit d\u2019Ormuz, et que les \u00c9tats-Unis ainsi que d\u2019autres pays refusent de reconna\u00eetre cette affirmation, le diff\u00e9rend ne&hellip;<\/p>\n","protected":false},"author":146,"featured_media":372957,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,4,5],"tags":[8835],"class_list":["post-392241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualites","category-politique","tag-detroit-dormuz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La force ou le droit ? Le d\u00e9troit d\u2019Ormuz et la mise \u00e0 l\u2019\u00e9preuve du syst\u00e8me international - R\u00e9alit\u00e9s Magazine<\/title>\n<meta name=\"description\" content=\"Lorsque l\u2019Iran affirme \u00eatre en mesure de contr\u00f4ler le trafic dans le d\u00e9troit d\u2019Ormuz, et que les \u00c9tats-Unis ainsi que d\u2019autres pays refusent de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La force ou le droit ? Le d\u00e9troit d\u2019Ormuz et la mise \u00e0 l\u2019\u00e9preuve du syst\u00e8me international - R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"og:description\" content=\"Lorsque l\u2019Iran affirme \u00eatre en mesure de contr\u00f4ler le trafic dans le d\u00e9troit d\u2019Ormuz, et que les \u00c9tats-Unis ainsi que d\u2019autres pays refusent de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9alit\u00e9s Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realites.tn\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T12:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/10\/Hichem-Karoui.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3142\" \/>\n\t<meta property=\"og:image:height\" content=\"2766\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hichem Karoui\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hichem Karoui\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/\",\"url\":\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/\",\"name\":\"La force ou le droit ? Le d\u00e9troit d\u2019Ormuz et la mise \u00e0 l\u2019\u00e9preuve du syst\u00e8me international - R\u00e9alit\u00e9s Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/10\/Hichem-Karoui.jpg\",\"datePublished\":\"2026-07-14T12:00:05+00:00\",\"author\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/f6efbf8668a6949b7394ef61ca7dfa73\"},\"description\":\"Lorsque l\u2019Iran affirme \u00eatre en mesure de contr\u00f4ler le trafic dans le d\u00e9troit d\u2019Ormuz, et que les \u00c9tats-Unis ainsi que d\u2019autres pays refusent de\",\"breadcrumb\":{\"@id\":\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#primaryimage\",\"url\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/10\/Hichem-Karoui.jpg\",\"contentUrl\":\"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/10\/Hichem-Karoui.jpg\",\"width\":3142,\"height\":2766},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/realites.com.tn\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La force ou le droit ? Le d\u00e9troit d\u2019Ormuz et la mise \u00e0 l\u2019\u00e9preuve du syst\u00e8me international\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#website\",\"url\":\"https:\/\/realites.com.tn\/fr\/\",\"name\":\"R\u00e9alit\u00e9s Magazine\",\"description\":\"Actualit\u00e9s de la Tunisie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/realites.com.tn\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/f6efbf8668a6949b7394ef61ca7dfa73\",\"name\":\"Hichem Karoui\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/98d610f3fce046fdf5eadc50a77e430d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/98d610f3fce046fdf5eadc50a77e430d?s=96&d=mm&r=g\",\"caption\":\"Hichem Karoui\"},\"url\":\"https:\/\/realites.com.tn\/fr\/author\/hichemk\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La force ou le droit ? Le d\u00e9troit d\u2019Ormuz et la mise \u00e0 l\u2019\u00e9preuve du syst\u00e8me international - R\u00e9alit\u00e9s Magazine","description":"Lorsque l\u2019Iran affirme \u00eatre en mesure de contr\u00f4ler le trafic dans le d\u00e9troit d\u2019Ormuz, et que les \u00c9tats-Unis ainsi que d\u2019autres pays refusent de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/","og_locale":"fr_FR","og_type":"article","og_title":"La force ou le droit ? Le d\u00e9troit d\u2019Ormuz et la mise \u00e0 l\u2019\u00e9preuve du syst\u00e8me international - R\u00e9alit\u00e9s Magazine","og_description":"Lorsque l\u2019Iran affirme \u00eatre en mesure de contr\u00f4ler le trafic dans le d\u00e9troit d\u2019Ormuz, et que les \u00c9tats-Unis ainsi que d\u2019autres pays refusent de","og_url":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/","og_site_name":"R\u00e9alit\u00e9s Magazine","article_publisher":"https:\/\/www.facebook.com\/realites.tn\/","article_published_time":"2026-07-14T12:00:05+00:00","og_image":[{"width":3142,"height":2766,"url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/10\/Hichem-Karoui.jpg","type":"image\/jpeg"}],"author":"Hichem Karoui","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Hichem Karoui","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/","url":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/","name":"La force ou le droit ? Le d\u00e9troit d\u2019Ormuz et la mise \u00e0 l\u2019\u00e9preuve du syst\u00e8me international - R\u00e9alit\u00e9s Magazine","isPartOf":{"@id":"https:\/\/realites.com.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#primaryimage"},"image":{"@id":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#primaryimage"},"thumbnailUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/10\/Hichem-Karoui.jpg","datePublished":"2026-07-14T12:00:05+00:00","author":{"@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/f6efbf8668a6949b7394ef61ca7dfa73"},"description":"Lorsque l\u2019Iran affirme \u00eatre en mesure de contr\u00f4ler le trafic dans le d\u00e9troit d\u2019Ormuz, et que les \u00c9tats-Unis ainsi que d\u2019autres pays refusent de","breadcrumb":{"@id":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#primaryimage","url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/10\/Hichem-Karoui.jpg","contentUrl":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/10\/Hichem-Karoui.jpg","width":3142,"height":2766},{"@type":"BreadcrumbList","@id":"https:\/\/realites.com.tn\/fr\/la-force-ou-le-droit-le-detroit-dormuz-et-la-mise-a-lepreuve-du-systeme-international\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/realites.com.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"La force ou le droit ? Le d\u00e9troit d\u2019Ormuz et la mise \u00e0 l\u2019\u00e9preuve du syst\u00e8me international"}]},{"@type":"WebSite","@id":"https:\/\/realites.com.tn\/fr\/#website","url":"https:\/\/realites.com.tn\/fr\/","name":"R\u00e9alit\u00e9s Magazine","description":"Actualit\u00e9s de la Tunisie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realites.com.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/f6efbf8668a6949b7394ef61ca7dfa73","name":"Hichem Karoui","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/realites.com.tn\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/98d610f3fce046fdf5eadc50a77e430d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98d610f3fce046fdf5eadc50a77e430d?s=96&d=mm&r=g","caption":"Hichem Karoui"},"url":"https:\/\/realites.com.tn\/fr\/author\/hichemk\/"}]}},"jetpack_featured_media_url":"https:\/\/realites.com.tn\/fr\/wp-content\/uploads\/2025\/10\/Hichem-Karoui.jpg","jetpack_sharing_enabled":true,"views":46,"_links":{"self":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/392241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/users\/146"}],"replies":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/comments?post=392241"}],"version-history":[{"count":1,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/392241\/revisions"}],"predecessor-version":[{"id":392242,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/posts\/392241\/revisions\/392242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media\/372957"}],"wp:attachment":[{"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/media?parent=392241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/categories?post=392241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realites.com.tn\/fr\/wp-json\/wp\/v2\/tags?post=392241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}